{"id":320796,"date":"2026-08-28T13:14:32","date_gmt":"2026-08-28T16:14:32","guid":{"rendered":"https:\/\/www.caririemacao.com\/1\/?p=320796"},"modified":"2026-08-28T13:14:32","modified_gmt":"2026-08-28T16:14:32","slug":"laudo-deve-apontar-em-30-dias-causa-do-incendio-no-centro-comercial-de-passagem-em-joao-pessoa","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2026\/08\/28\/laudo-deve-apontar-em-30-dias-causa-do-incendio-no-centro-comercial-de-passagem-em-joao-pessoa\/","title":{"rendered":"Laudo deve apontar em 30 dias causa do inc\u00eandio no Centro Comercial de Passagem, em Jo\u00e3o Pessoa"},"content":{"rendered":"<p> Inc\u00eandio \u00e9 registrado em centro comercial de Jo\u00e3o Pessoa<br \/>\nUma per\u00edcia foi realizada na manh\u00e3 desta sexta-feira (28), no Centro Comercial de Passagem, no Parque S\u00f3lon de Lucena, em Jo\u00e3o Pessoa, para investigar as causas do inc\u00eandio que atingiu o local na quinta-feira (27). Segundo o Corpo de Bombeiros, um laudo com as poss\u00edveis causas do inc\u00eandio deve ser emitido em at\u00e9 30 dias.<\/p>\n<p>Quatro lojas foram totalmente destru\u00eddas em inc\u00eandio no Centro de Passagem<br \/>\nTestemunhas de inc\u00eandio no Centro de Passagem relatam correria com as chamas, em Jo\u00e3o Pessoa<br \/>\nDe acordo com o Corpo de Bombeiros Militar da Para\u00edba, a perita respons\u00e1vel fez levantamento e an\u00e1lises t\u00e9cnicas necess\u00e1rias durante a per\u00edcia. O procedimento \u00e9 necess\u00e1rio para o levantamento de vest\u00edgios que possam auxiliar na identifica\u00e7\u00e3o da prov\u00e1vel causa do inc\u00eandio. Ainda de acordo com os bombeiros, a perita tem at\u00e9 30 dias para elaborar o laudo.<\/p>\n<p>A causa do inc\u00eandio s\u00f3 poder\u00e1 ser indicada ap\u00f3s a conclus\u00e3o desse laudo. O local foi entregue aos cuidados da Secretaria de Desenvolvimento Urbano (Sedurb) de Jo\u00e3o Pessoa ap\u00f3s a per\u00edcia. V\u00eddeos em alta no g1<br \/>\nInc\u00eandio destruiu totalmente quatro lojas<br \/>\nInc\u00eandio atinge Centro Comercial de Passagem, em Jo\u00e3o Pessoa<br \/>\nMontagem\/g1<br \/>\nUm inc\u00eandio atingiu o Centro Comercial de Passagem, localizado no Parque S\u00f3lon de Lucena, no Centro de Jo\u00e3o Pessoa, na tarde desta quinta-feira (27).<\/p>\n<p>O Corpo de Bombeiros informou, no come\u00e7o da noite, que pelo menos sete pessoas precisaram ser atendidas por inala\u00e7\u00e3o de fuma\u00e7a, sem queimaduras ou gravidades. Comerciantes relataram \u00e0 equipe da TV Cabo Branco que os extintores do centro comercial estavam funcionando, mas que os hidrantes n\u00e3o teriam funcionado durante o inc\u00eandio. Segundo Sabrina, a Diretoria de Atividades T\u00e9cnicas do Corpo de Bombeiros vai verificar a situa\u00e7\u00e3o.<\/p>\n<p>O fogo foi controlado pelas equipes do Corpo de Bombeiros por volta das 18h15. No entanto, um novo foco de inc\u00eandio foi registrado por volta das 19h20 e tamb\u00e9m foi controlado. O Centro Comercial de Passagem (CCP) foi inaugurado em 2006.<\/p>\n<p>Localizado no Parque S\u00f3lon de Lucena, o espa\u00e7o possui 297 pontos comerciais, que vendem produtos como pe\u00e7as de vestu\u00e1rio, eletr\u00f4nicos e alimentos. V\u00eddeos mais assistidos do g1 Para\u00edba<\/p>\n<p><em>Fonte: G1 Para\u00edba<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inc\u00eandio \u00e9 registrado em centro comercial de Jo\u00e3o Pessoa Uma per\u00edcia foi realizada na manh\u00e3 desta sexta-feira (28), no Centro Comercial de Passagem, no Parque S\u00f3lon de Lucena, em Jo\u00e3o Pessoa, para investigar as causas do inc\u00eandio que atingiu o local na quinta-feira (27). Segundo o Corpo de Bombeiros, um laudo com as poss\u00edveis causas do inc\u00eandio deve ser emitido em at\u00e9 30 dias. LEIA TAMB\u00c9M Quatro lojas foram totalmente destru\u00eddas em inc\u00eandio no Centro de Passagem Testemunhas de inc\u00eandio no Centro de Passagem relatam correria com as chamas, em Jo\u00e3o Pessoa De acordo com o Corpo de Bombeiros Militar da Para\u00edba, a perita respons\u00e1vel fez levantamento e an\u00e1lises t\u00e9cnicas necess\u00e1rias durante a per\u00edcia. O procedimento \u00e9 necess\u00e1rio para o levantamento de vest\u00edgios que possam auxiliar na identifica\u00e7\u00e3o da prov\u00e1vel causa do inc\u00eandio. &#x2705; Clique aqui para seguir o canal do g1 PB no WhatsApp Ainda de acordo com os bombeiros, a perita tem at\u00e9 30 dias para elaborar o laudo. A causa do inc\u00eandio s\u00f3 poder\u00e1 ser indicada ap\u00f3s a conclus\u00e3o desse laudo. O local foi entregue aos cuidados da Secretaria de Desenvolvimento Urbano (Sedurb) de Jo\u00e3o Pessoa ap\u00f3s a per\u00edcia. V\u00eddeos em alta no g1 Inc\u00eandio destruiu totalmente quatro lojas Inc\u00eandio atinge Centro Comercial de Passagem, em Jo\u00e3o Pessoa Montagem\/g1 Um inc\u00eandio atingiu o Centro Comercial de Passagem, localizado no Parque S\u00f3lon de Lucena, no Centro de Jo\u00e3o Pessoa, na tarde desta quinta-feira (27). O Corpo de Bombeiros informou, no come\u00e7o da noite, que pelo menos sete pessoas precisaram ser atendidas por inala\u00e7\u00e3o de fuma\u00e7a, sem queimaduras ou gravidades. Comerciantes relataram \u00e0 equipe da TV Cabo Branco que os extintores do centro comercial estavam funcionando, mas que os hidrantes n\u00e3o teriam funcionado durante o inc\u00eandio. Segundo Sabrina, a Diretoria de Atividades T\u00e9cnicas do Corpo de Bombeiros vai verificar a situa\u00e7\u00e3o. O fogo foi controlado pelas equipes do Corpo de Bombeiros por volta das 18h15. No entanto, um novo foco de inc\u00eandio foi registrado por volta das 19h20 e tamb\u00e9m foi controlado. O Centro Comercial de Passagem (CCP) foi inaugurado em 2006. Localizado no Parque S\u00f3lon de Lucena, o espa\u00e7o possui 297 pontos comerciais, que vendem produtos como pe\u00e7as de vestu\u00e1rio, eletr\u00f4nicos e alimentos. V\u00eddeos mais assistidos do g1 Para\u00edba<\/p>\n","protected":false},"author":0,"featured_media":320797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[104],"tags":[],"class_list":["post-320796","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paraiba"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/320796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=320796"}],"version-history":[{"count":1,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/320796\/revisions"}],"predecessor-version":[{"id":320798,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/320796\/revisions\/320798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/320797"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=320796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=320796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=320796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}