{"id":32912,"date":"2017-11-11T01:31:55","date_gmt":"2017-11-11T04:31:55","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=32912"},"modified":"2017-11-11T01:31:55","modified_gmt":"2017-11-11T04:31:55","slug":"inep-altera-data-de-aplicacao-do-encceja","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/11\/11\/inep-altera-data-de-aplicacao-do-encceja\/","title":{"rendered":"Inep altera data de aplica\u00e7\u00e3o do Encceja"},"content":{"rendered":"<p>O Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep) informou hoje (10) que a data da aplica\u00e7\u00e3o da edi\u00e7\u00e3o de 2017 do Exame Nacional para Certifica\u00e7\u00e3o de Compet\u00eancias de Jovens e Adultos para Pessoas Privadas de Liberdade e jovens sob medida socioeducativa que inclua priva\u00e7\u00e3o de liberdade (Encceja) foi modificada e ocorrer\u00e1, agora, nos dias 19 e 20 de dezembro.<\/p>\n<p>Anteriormente, o exame seria realizado nos dias 21 e 22 de novembro.<\/p>\n<p>De acordo com o Inep, a mudan\u00e7a ocorreu devido a \u201cadequa\u00e7\u00e3o de log\u00edstica\u201d entre o instituto e o Departamento Penitenci\u00e1rio Nacional (Depen), em virtude da proximidade da realiza\u00e7\u00e3o do Exame Nacional do Ensino M\u00e9dio (Enem), que tem o segundo e \u00faltimo dia de provas neste domingo (12).<\/p>\n<p>O Encceja \u00e9 direcionado \u00e0s pessoas que n\u00e3o tiveram a oportunidade de concluir seus estudos em idade pr\u00f3pria. Os participantes que buscam a certifica\u00e7\u00e3o do ensino fundamental precisam ter, no m\u00ednimo, 15 anos completos na data da prova. Quem busca a certifica\u00e7\u00e3o do ensino m\u00e9dio tem que ter, no m\u00ednimo, 18 anos completos.<\/p>\n<p>O exame ser\u00e1 realizado nas unidades prisionais e socioeducativas indicadas pelos \u00f3rg\u00e3os competentes e ser\u00e1 dividido em quatro provas objetivas, por n\u00edvel de ensino, e uma reda\u00e7\u00e3o. Cada prova objetiva tem 30 quest\u00f5es de m\u00faltipla escolha.<\/p>\n<p>Cada unidade prisional ou socioeducativa tem um respons\u00e1vel pedag\u00f3gico com acesso ao sistema de inscri\u00e7\u00e3o e suas funcionalidades. Al\u00e9m de respons\u00e1vel pela realiza\u00e7\u00e3o e acompanhamento das inscri\u00e7\u00f5es, compete a ele a obriga\u00e7\u00e3o de realizar o ensalamento e a exclus\u00e3o de participantes que tiverem sua liberdade decretada.<\/p>\n<p>Ainda segundo o Inep, o respons\u00e1vel pedag\u00f3gico acessar\u00e1 os resultados obtidos pelos participantes, pleitear\u00e1 sua participa\u00e7\u00e3o no Sistema de Sele\u00e7\u00e3o Unificada (Sisu) e em outros programas de acesso ao ensino superior.<\/p>\n<p>O respons\u00e1vel pedag\u00f3gico tamb\u00e9m fica respons\u00e1vel por divulgar as informa\u00e7\u00f5es sobre o exame aos participantes.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com Ag\u00eancia Brasil\u00a0\/Foto: Google\u00a0\u00a0 <\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a>,<strong>\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\"><strong>Instagram<\/strong><\/a><strong>\u00a0e <\/strong><a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\"><strong>Youtube<\/strong><\/a><strong>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Nacional de Estudos e Pesquisas Educacionais An\u00edsio Teixeira (Inep) informou hoje (10) que a data da aplica\u00e7\u00e3o da edi\u00e7\u00e3o de 2017 do Exame&hellip; <\/p>\n","protected":false},"author":2,"featured_media":13400,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[14],"tags":[],"class_list":["post-32912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/32912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=32912"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/32912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/13400"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=32912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=32912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=32912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}