{"id":32920,"date":"2017-11-11T01:46:47","date_gmt":"2017-11-11T04:46:47","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=32920"},"modified":"2017-11-11T01:46:47","modified_gmt":"2017-11-11T04:46:47","slug":"bandidos-voltam-a-aterrorizar-em-monteiro","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/11\/11\/bandidos-voltam-a-aterrorizar-em-monteiro\/","title":{"rendered":"Bandidos voltam a aterrorizar em Monteiro"},"content":{"rendered":"<p>Uma moto foi roubada e outra foi furtada na noite desta sexta-feira (10), no munic\u00edpio de Monteiro, no Cariri paraibano. O munic\u00edpio vem sofrendo com os altos \u00edndices de assaltos nos \u00faltimos meses, que tem amedrontando a popula\u00e7\u00e3o.<\/p>\n<p>No primeiro caso, uma moto Honda Bros 160 de cor preta, placa PCW-0597, na BR-412, mas precisamente, pr\u00f3ximo \u00e0 agrovila Lafayte. Conforme o propriet\u00e1rio da moto, dois homens em outra motocicleta se aproximaram e anunciaram o assalto com arma em punho.<\/p>\n<p>A v\u00edtima relatou ainda, que os assaltantes fugiram com destino a cidade de Monteiro.<\/p>\n<p>J\u00e1 no segundo caso, o propriet\u00e1rio da moto Honda CG 150 de Cor Azul, placa KJB-7506, modelo 2005, estacionou a moto na cal\u00e7ada de uma resid\u00eancia e entrou. Minutos depois ao sair, n\u00e3o encontrou mais a moto, que havia sido furtada.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com Cariri Ligado\/<\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a>,<strong>\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\"><strong>Instagram<\/strong><\/a><strong>\u00a0e <\/strong><a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\"><strong>Youtube<\/strong><\/a><strong>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma moto foi roubada e outra foi furtada na noite desta sexta-feira (10), no munic\u00edpio de Monteiro, no Cariri paraibano. O munic\u00edpio vem sofrendo com&hellip; <\/p>\n","protected":false},"author":2,"featured_media":25307,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-32920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/32920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=32920"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/32920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/25307"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=32920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=32920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=32920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}