{"id":32931,"date":"2017-11-11T02:07:12","date_gmt":"2017-11-11T05:07:12","guid":{"rendered":"http:\/\/caririemacao.com\/1\/?p=32931"},"modified":"2017-11-11T02:10:09","modified_gmt":"2017-11-11T05:10:09","slug":"32931","status":"publish","type":"post","link":"https:\/\/www.caririemacao.com\/1\/2017\/11\/11\/32931\/","title":{"rendered":"Governo n\u00e3o garante repasse de recursos e universidades podem ter 2018 de crise"},"content":{"rendered":"<p>O Governo Federal ainda n\u00e3o garantiu o repasse de recursos para Universidades Federais para o ano de 2018 e a incerteza sobre a verba tem deixado reitores de todo o Nordeste preocupados com a situa\u00e7\u00e3o em que as institui\u00e7\u00f5es se encontram atualmente. A problem\u00e1tica foi exposta nesta sexta-feira (10) durante encontro realizado na Universidade Federal da Para\u00edba (UFPB), onde o reitor da Universidade Federal do Piau\u00ed e vice-presidente da Associa\u00e7\u00e3o Nacional dos Dirigentes das Institui\u00e7\u00f5es Federais de Ensino Superior (Andifes), Arimateia Lopes, exp\u00f4s que at\u00e9 o momento o recurso garantido \u00e9 relativo a apenas 15% do que foi enviado em 2017.<\/p>\n<p>\u201cN\u00f3s tivemos uma diminui\u00e7\u00e3o no recurso das universidades em um valor muito alto, um percentual alto O MEC (Minist\u00e9rio da Educa\u00e7\u00e3o) alega que o or\u00e7amento tem crescido. Realmente se voc\u00ea envolver a folha de pagamento \u00e9 claro que cresce, porque est\u00e1 dentro do crescimento vegetativo da folha, mas quando voc\u00ea tira o pessoal, que a gente foca que \u00e9 o recurso para custeio e investimento, a\u00ed houve uma redu\u00e7\u00e3o significante. No custeio, n\u00f3s tivemos a manuten\u00e7\u00e3o do valor nominal do ano passado, o que significa uma redu\u00e7\u00e3o levando em conta a infla\u00e7\u00e3o. E no capital, uma redu\u00e7\u00e3o dr\u00e1stica, em torno de 50% dos recursos de 2016 que foram liberados para 2017. E para 2018, estamos em uma situa\u00e7\u00e3o mais cr\u00edtica, porque o que tem alocado para or\u00e7amentos das universidades chega a 15% deste ano\u201d, explicou.<\/p>\n<p>A reitora da UFPB, Margareth Diniz, tratou como lament\u00e1vel a atual conjuntura e ressaltou a import\u00e2ncia do ensino superior p\u00fablico e gratuito. \u2018\u00c9 lament\u00e1vel esta situa\u00e7\u00e3o. Mas estamos firmes e fortes na vontade de que a gente possa mostrar para a sociedade e a este governo a import\u00e2ncia de que se \u00e9 ter uma universidade funcionando em sua plenitude e que o repasse de recursos para universidades publicas \u00e9 investimento. Se voc\u00ea observar o FIES, que \u00e9 o repasse do governo para universidades e faculdades privadas, em 2001 foi de 2,1 bilh\u00f5es de reais, em 2017 de R$ 21 bilh\u00f5es. As universidades publicas federais s\u00f3 precisam de seis bilh\u00f5es para seu custeio no dia a dia. Ent\u00e3o n\u00e3o \u00e9 proporcional como ele v\u00ea a universidade publica federal e v\u00ea as universidades privadas? N\u00f3s lamentamos muito por isto\u201d, disse.<\/p>\n<p>Segundo a reitora, a situa\u00e7\u00e3o \u00e9 praticamente igual em todas as universidades do Brasil. \u201cA situa\u00e7\u00e3o \u00e9 linear para todas as universidades federais do Brasil e n\u00f3s lamentamos que o governo tenha centrado muito nas universidades p\u00fablicas federais para cortar o nosso or\u00e7amento. Temos a clareza da import\u00e2ncia que \u00e9 uma universidade p\u00fablica gratuita e de qualidade, n\u00e3o abrimos m\u00e3o disto. Estamos batalhando pelo futuro do nosso pa\u00eds. As universidades federais s\u00e3o respons\u00e1veis pela maioria do que se faz em pesquisa e inova\u00e7\u00e3o tecnol\u00f3gica, e atrav\u00e9s da educa\u00e7\u00e3o que nos vamos emancipar o nosso povo, os nossos jovens\u201d, explicou.<\/p>\n<p><strong>CARIRI EM A\u00c7\u00c3O<\/strong><\/p>\n<p><em>Com Portal Correio\/Foto: Google\u00a0\u00a0 <\/em><\/p>\n<p><strong>Leia mais not\u00edcias em\u00a0<\/strong><a href=\"http:\/\/www.caririemacao.com\/\"><strong>caririemacao.com<\/strong><\/a><strong>, siga nossa p\u00e1gina no\u00a0<\/strong><a href=\"https:\/\/www.facebook.com\/CaririEmAcao\/?ref=aymt_homepage_panel\"><strong>Facebook<\/strong><\/a>,<strong>\u00a0<\/strong><a href=\"https:\/\/www.instagram.com\/cariri_em_acao\/?hl=pt-br\"><strong>Instagram<\/strong><\/a><strong>\u00a0e <\/strong><a href=\"https:\/\/www.youtube.com\/channel\/UCAptA0jQuYQy8vMhLt2m4qg\"><strong>Youtube<\/strong><\/a><strong>\u00a0e veja nossas mat\u00e9rias, v\u00eddeos e fotos. Voc\u00ea tamb\u00e9m pode enviar informa\u00e7\u00f5es \u00e0 Reda\u00e7\u00e3o do Portal Cariri em A\u00e7\u00e3o pelo WhatsApp (83) 9 9634.5791, (83) 9 9601-1162.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Governo Federal ainda n\u00e3o garantiu o repasse de recursos para Universidades Federais para o ano de 2018 e a incerteza sobre a verba tem&hellip; <\/p>\n","protected":false},"author":2,"featured_media":24818,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"sfsi_plus_gutenberg_text_before_share":"","sfsi_plus_gutenberg_show_text_before_share":"","sfsi_plus_gutenberg_icon_type":"","sfsi_plus_gutenberg_icon_alignemt":"","sfsi_plus_gutenburg_max_per_row":"","footnotes":""},"categories":[14],"tags":[],"class_list":["post-32931","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao"],"_links":{"self":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/32931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/comments?post=32931"}],"version-history":[{"count":0,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/posts\/32931\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media\/24818"}],"wp:attachment":[{"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/media?parent=32931"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/categories?post=32931"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.caririemacao.com\/1\/wp-json\/wp\/v2\/tags?post=32931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}